{"id":40583,"date":"2020-09-14T16:07:49","date_gmt":"2020-09-14T14:07:49","guid":{"rendered":"https:\/\/shiatsuverband.ch\/?p=40583"},"modified":"2021-08-19T10:29:00","modified_gmt":"2021-08-19T08:29:00","slug":"comprendre-la-therapie-en-tant-que-processus","status":"publish","type":"post","link":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/","title":{"rendered":"Comprendre la th\u00e9rapie en tant que processus"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k0f7b5nc-cab06104f7ac28d03f5e46fabae8d83e\">\n.avia-image-container.av-k0f7b5nc-cab06104f7ac28d03f5e46fabae8d83e img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k0f7b5nc-cab06104f7ac28d03f5e46fabae8d83e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k0f7b5nc-cab06104f7ac28d03f5e46fabae8d83e av-styling- avia-align-center  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-40572 avia-img-lazy-loading-not-40572 avia_image ' src=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg\" alt='' title='Vorlage_Hintergrund_Blog'  height=\"552\" width=\"1600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg 1600w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-300x104.jpg 300w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-1030x355.jpg 1030w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-768x265.jpg 768w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-1536x530.jpg 1536w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-1500x518.jpg 1500w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE-705x243.jpg 705w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div><\/div><\/div>\n<section  class='av_textblock_section av-k0f7brzh-ca7b4d3d3bb5dc3df04a9145ce98a35d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>La th\u00e9rapie \u2013 un processus<\/h1>\n<p><strong>Entretien avec Barbara Felber, membre du comit\u00e9 de l\u2019Association Suisse de Shiatsu (ASS)<\/strong><\/p>\n<p><strong>Dans la th\u00e9rapie compl\u00e9mentaire, la gu\u00e9rison est interpr\u00e9t\u00e9e comme un processus de transformation individuel qui englobe le corps, l\u2019\u00e2me et l\u2019esprit et qui est influenc\u00e9 par diff\u00e9rents facteurs qui se compl\u00e8tent mutuellement. La th\u00e9rapie a comme objectif d\u2019initier ce processus, de lui accorder de l\u2019espace et de l\u2019accompagner \u00e0 travers diverses phases. Elle vise \u00e0 stimuler la perception et la prise de conscience de soi, \u00e0 renforcer l\u2019autor\u00e9gulation et \u00e0 consolider la comp\u00e9tence personnelle de gu\u00e9rison dans l\u2019objectif de rem\u00e9dier aux restrictions et aux troubles physiques, \u00e9motionnelles et mentales. Le processus de gu\u00e9rison personnel est en outre soutenu par le renforcement de ressources et de capacit\u00e9s individuelles.<\/strong><\/p>\n<p><strong>Qu\u2019est-ce qu\u2019il faut comprendre par processus th\u00e9rapeutique dans le Shiatsu ?<\/strong><br \/>\nSelon les principes de la philosophie de l\u2019Extr\u00eame-Orient constituant la base du Shiatsu, il faut comprendre la vie comme un processus de transformation constant qui englobe tout. Si l\u2019\u00eatre humain n\u2019est pas en harmonie avec les changements qui ont lieu dans son corps, dans sa vie, dans son environnement ou dans le monde et qu\u2019il n\u2019arrive pas \u00e0 suffisamment s\u2019adapter, il perd son \u00e9quilibre, ce qui peut se manifester par des troubles physiques, \u00e9motionnelles ou mentales. A l\u2019inverse, la gu\u00e9rison repr\u00e9sente le processus qui m\u00e8ne au r\u00e9tablissement de l\u2019\u00e9quilibre dans les circonstances donn\u00e9es. La sant\u00e9 n\u2019est donc pas un \u00e9tat statique mais plut\u00f4t un processus de r\u00e9gulation constant qui passe par des phases plus ou moins id\u00e9ales.<\/p>\n<p>Cette recherche du meilleur \u00e9quilibre possible est un processus de transformation individuel. Dans la th\u00e9rapie de Shiatsu, l\u2019observation de ce processus sert constamment d\u2019orientation (p.ex. lors du bilan \u00e9nerg\u00e9tique) en vue d\u2019un soutien et d\u2019un accompagnement optimal.<\/p>\n<p>Afin de pouvoir r\u00e9pondre au mieux \u00e0 ce processus de r\u00e9gulation, la structure de la th\u00e9rapie doit, elle aussi, reposer sur le processus : on d\u00e9nombre quatre phases de processus dans la th\u00e9rapie de Shiatsu. Celles-ci peuvent aussi se chevaucher ou appara\u00eetre de mani\u00e8re non-lin\u00e9aire. Dans chaque phase, il s\u2019agit de comprendre la personne dans son enti\u00e8ret\u00e9 et d\u2019accompagner les changements au niveau du corps, de l\u2019esprit ou des \u00e9motions, suivant la priorit\u00e9.<\/p>\n<p><strong>Quelles sont les phases de processus et qu&rsquo;est-ce qui les caract\u00e9rise ?<\/strong><br \/>\nDans la th\u00e9rapie compl\u00e9mentaire dont le Shiatsu fait partie, on peut d\u00e9nombrer quatre phases de processus : <em>Rencontrer, Travailler, Int\u00e9grer <\/em>et <em>Transf\u00e9rer<\/em>.<\/p>\n<p>La phase de la <em>Rencontre<\/em> engage le processus th\u00e9rapeutique. Elle a comme objectif d\u2019\u00e9tablir une relation et d\u2019instaurer un climat de confiance, d\u2019ouverture et de s\u00e9curit\u00e9 qui permettra \u00e0 la cliente de s\u2019ouvrir \u00e0 soi-m\u00eame et de se consacrer \u00e0 son processus de gu\u00e9rison. Le bilan \u00e9nerg\u00e9tique, l\u2019appr\u00e9ciation de la situation individuelle et l\u2019identification des ressources dont la cliente est consciente font \u00e9galement partie de cette phase.<\/p>\n<p>La phase du <em>Travail <\/em>comprend la partie de la th\u00e9rapie qui est sp\u00e9cifique \u00e0 la m\u00e9thode. Lors de cette phase seront trait\u00e9s les th\u00e8mes, les troubles ou les restrictions existants et ceux qui surgissent pendant le processus, aux niveaux physique, \u00e9nerg\u00e9tique (par les m\u00e9ridiens), \u00e9motionnel ou mental. Dans le processus du <em>Travail<\/em>, il peut y avoir aussi des ressources cach\u00e9es qui font surface. Dans cette phase, le travail est particuli\u00e8rement centr\u00e9 sur la perception et la prise de conscience de soi afin d\u2019entrer en contact avec les th\u00e8mes et les troubles \u00e9mergents, mais aussi avec des comp\u00e9tences. Le processus qui a \u00e9t\u00e9 mis en place par la reconnaissance et l\u2019acceptation des th\u00e8mes qui surgissent et le traitement \u00e9nerg\u00e9tique des m\u00e9ridiens apportent souvent d\u00e9j\u00e0 une certaine autor\u00e9gulation et d\u00e9tente.<\/p>\n<p>La phase <em>d\u2019Int\u00e9gration <\/em>\u00e0 son tour permettra de remettre les choses \u00e0 leur place. La sensation d\u2019int\u00e9gration ressemble au fait de dire \u00ab\u00a0oui\u00a0\u00bb. Les int\u00e9grations \u00e9nerg\u00e9tiques sp\u00e9cifiques aux m\u00e9ridiens s\u2019expriment par de profondes respirations et par la d\u00e9tente. Les int\u00e9grations \u00e9motionnelles ou mentales s\u2019accompagnent d\u2019une prise de conscience, de compr\u00e9hension et d\u2019un d\u00e9sir de changement.<\/p>\n<p>La phase de <em>Transfert <\/em>vise \u00e0 int\u00e9grer les impulsions des phases pr\u00e9c\u00e9dentes dans le quotidien. L\u2019objectif sera de consolider la prise de conscience et les changements qui en d\u00e9coulent avec des exercices, des visualisations et un comportement diff\u00e9rent dans la vie de tous les jours.<\/p>\n<p><strong>Peux-tu d\u00e9crire le processus pendant la th\u00e9rapie \u00e0 l\u2019aide d\u2019un exemple pratique ?<\/strong><br \/>\nUn client m\u2019a consult\u00e9 apr\u00e8s une suite de petits accidents. D\u2019un point de vue m\u00e9dical, il \u00e9tait gu\u00e9ri, mais il souffrait toujours de maux de t\u00eate, de vertiges et d\u2019une forte hypersensibilit\u00e9 au bruit, \u00e0 tel point qu\u2019il \u00e9tait incapable de travailler. Il \u00e9tait plut\u00f4t sceptique quant \u00e0 l\u2019efficacit\u00e9 de la m\u00e9thode, mais son m\u00e9decin traitant lui avait recommand\u00e9 le Shiatsu. Or, comme il se sentait bien compris pendant la phase de la <em>Rencontre, <\/em>il gagnait en confiance et en d\u00e9pit de son attitude r\u00e9serv\u00e9e dont il avait fait montre initialement, il commen\u00e7ait \u00e0 parler davantage de lui-m\u00eame. Il racontait qu\u2019il \u00e9tait constamment surcharg\u00e9 au travail et d\u00e9pass\u00e9 par le quotidien familial. \u00c0 la suite de ses accidents, il avait \u00e9t\u00e9 forc\u00e9 de s\u2019arr\u00eater et de se calmer pour la premi\u00e8re fois depuis des ann\u00e9es.<\/p>\n<p>Pendant la phase de <em>Travail<\/em>, nous avons lib\u00e9r\u00e9 des tensions et blocages au moyen d\u2019un travail corporel avec l\u2019\u00e9nergie des m\u00e9ridiens. Dans cette phase, gr\u00e2ce \u00e0 une perception accrue de son corps, le client a pris conscience de la g\u00eane qu\u2019il ressentait quand tout devenait calme et silencieux. Il a pu formuler cette g\u00eane pendant la th\u00e9rapie et a compris son contexte pendant l\u2019entretien, ce qui l\u2019a aid\u00e9 \u00e0 mieux se d\u00e9tendre lors des s\u00e9ances suivantes.<\/p>\n<p>Lors de la phase d\u2019<em>Int\u00e9gration,<\/em> nous avons explor\u00e9 les impacts que ces prises de conscience pourraient avoir dans sa vie. Il a appris quelques techniques de respiration qui l\u2019aidaient \u00e0 rester centr\u00e9 pendant les traitements, mais aussi dans la vie quotidienne. Puis peu \u00e0 peu, le d\u00e9sir de pouvoir cesser de courir apr\u00e8s le temps grandissait.<\/p>\n<p>Pendant la phase de <em>Transfert<\/em>, nous avons examin\u00e9 ensemble comment il pourrait r\u00e9aliser ses d\u00e9sirs au quotidien. Le client s\u2019est fix\u00e9 l\u2019objectif de prendre des moments clairement d\u00e9finis de r\u00e9flexion sur soi et de calme \u00e0 vivre consciemment. Il voulait aussi \u00eatre plus \u00e0 l\u2019\u00e9coute de son corps et de ses messages. Les ressources qui le soutenaient dans la r\u00e9alisation de ces changements \u00e9taient sa pers\u00e9v\u00e9rance et sa famille.<\/p>\n<p>Gr\u00e2ce \u00e0 ce processus, son \u00e9tat de sant\u00e9 s\u2019\u00e9tait continuellement am\u00e9lior\u00e9 et il avait recouvert sa capacit\u00e9 de travailler. Mais il se donnait la possibilit\u00e9 de reprendre son travail progressivement et prenait r\u00e9guli\u00e8rement du temps pour soi. Il apprenait \u00e0 reconna\u00eetre et respecter les besoins de son corps et \u00e0 faire face aux exigences de son entourage avec plus de s\u00e9r\u00e9nit\u00e9.<\/p>\n<p>Lors de sa derni\u00e8re s\u00e9ance, il mentionnait que m\u00eame les troubles du sommeil dont il avait souffert pendant plus de 20 ans, avaient disparu et qu\u2019il ne s\u2019\u00e9tait pas senti aussi calme et serein depuis des ann\u00e9es.<\/p>\n<\/div><\/section>\n<div  class='hr av-ocj83i-59e4689de3ae81f0340c8712ad1409f1 hr-default  avia-builder-el-2  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-k0f7brzh-7b9a835a3a065f358b235a5b16b0f82d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>L\u2019exp\u00e9rience pratique m\u2019a montr\u00e9 que le processus de r\u00e9gulation individuel \u00e9volue toujours de mani\u00e8re unique et naturelle, parfois aussi de fa\u00e7on in\u00e9gale ou impr\u00e9vue.<\/p>\n<p>La profondeur et la complexit\u00e9 du processus de gu\u00e9rison se montrent aussi dans le fait que gr\u00e2ce \u00e0 un accompagnement tr\u00e8s attentif et conscient et la reconnaissance et l\u2019acceptation de l\u2019\u00e9tat actuel des choses, de nouvelles voies inexplor\u00e9es peuvent s\u2019ouvrir vers le meilleur \u00e9quilibre possible.<\/p>\n<h1>La gu\u00e9rison dans la th\u00e9rapie compl\u00e9mentaire<\/h1>\n<p><strong>Autres contributions \u00e0 ce sujet\u00a0<\/strong><br \/>\n<a href=\"https:\/\/shiatsuverband.ch\/fr\/la-therapie-complementaire-en-tant-que-profession-de-la-sante\/\" target=\"_blank\" rel=\"noopener\">_ La th\u00e9rapie compl\u00e9mentaire en tant que profession de la sant\u00e9<strong><br \/>\n<\/strong><\/a><a href=\"https:\/\/shiatsuverband.ch\/fr\/la-guerison-dans-la-therapie-complementaire\/\" target=\"_blank\" rel=\"noopener\">_ La gu\u00e9rison dans la th\u00e9rapie compl\u00e9mentaire<\/a><\/p>\n<\/div><\/section>\n<div id='avia-messagebox-' class='avia_message_box av_notification av-jttwk962-6ffb5cbecb36fa022acefc2b4e02ed5d avia-color-grey avia-size-normal avia-icon_select-no avia-border-  avia-builder-el-4  el_after_av_textblock  el_before_av_textblock ' ><div class=\"avia_message_box_content\"><p><strong>Donn\u00e9es biographiques<\/strong><br \/>\nBarbara Felber est th\u00e9rapeute de Shiatsu depuis 22 ans. Elle travaille dans son propre cabinet \u00e0 Gen\u00e8ve. Au sein du comit\u00e9 de l\u2019ASS, elle est responsable de la m\u00e9thode Shiatsu. Dans ce cadre, elle avait particip\u00e9 \u00e0 l\u2019\u00e9laboration de l\u2019IDMET Shiatsu. Par ailleurs, elle est charg\u00e9e de la commission de r\u00e9daction, de la commission de formation continue et de la communication avec la Suisse romande.<\/p>\n<\/div><\/div>\n<section  class='av_textblock_section av-kf2l4zvk-f46a7907a45916ecb338cf9d946934c0 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><a href=\"https:\/\/shiatsuverband.ch\/fr\/association\/team\/barbara-felber\/\" target=\"_blank\" rel=\"noopener\">Link Team<\/a><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Dans la th\u00e9rapie compl\u00e9mentaire, la gu\u00e9rison est interpr\u00e9t\u00e9e comme un processus de transformation individuel qui englobe le corps, l\u2019\u00e2me et l\u2019esprit et qui est influenc\u00e9 par diff\u00e9rents facteurs qui se compl\u00e8tent mutuellement. La th\u00e9rapie a comme objectif d\u2019initier ce processus, de lui accorder de l\u2019espace et de l\u2019accompagner \u00e0 travers diverses phases. Elle vise \u00e0 stimuler la perception et la prise de conscience de soi, \u00e0 renforcer l\u2019autor\u00e9gulation et \u00e0 consolider la comp\u00e9tence personnelle de gu\u00e9rison dans l\u2019objectif de rem\u00e9dier aux restrictions et aux troubles physiques, \u00e9motionnelles et mentales. Le processus de gu\u00e9rison personnel est en outre soutenu par le renforcement de ressources et de capacit\u00e9s individuelles.<\/p>\n","protected":false},"author":5,"featured_media":40572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-40583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pratique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"og:description\" content=\"Dans la th\u00e9rapie compl\u00e9mentaire, la gu\u00e9rison est interpr\u00e9t\u00e9e comme un processus de transformation individuel qui englobe le corps, l\u2019\u00e2me et l\u2019esprit et qui est influenc\u00e9 par diff\u00e9rents facteurs qui se compl\u00e8tent mutuellement. La th\u00e9rapie a comme objectif d\u2019initier ce processus, de lui accorder de l\u2019espace et de l\u2019accompagner \u00e0 travers diverses phases. Elle vise \u00e0 stimuler la perception et la prise de conscience de soi, \u00e0 renforcer l\u2019autor\u00e9gulation et \u00e0 consolider la comp\u00e9tence personnelle de gu\u00e9rison dans l\u2019objectif de rem\u00e9dier aux restrictions et aux troubles physiques, \u00e9motionnelles et mentales. Le processus de gu\u00e9rison personnel est en outre soutenu par le renforcement de ressources et de capacit\u00e9s individuelles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/\" \/>\n<meta property=\"og:site_name\" content=\"Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T14:07:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T08:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Therapeutenliste Manager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Therapeutenliste Manager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/\"},\"author\":{\"name\":\"Therapeutenliste Manager\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ab3e3b203dc15a09f4da553818d7ffb9\"},\"headline\":\"Comprendre la th\u00e9rapie en tant que processus\",\"datePublished\":\"2020-09-14T14:07:49+00:00\",\"dateModified\":\"2021-08-19T08:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/\"},\"wordCount\":1708,\"publisher\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Blog_BFE.jpg\",\"articleSection\":[\"Pratique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/\",\"name\":\"Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Blog_BFE.jpg\",\"datePublished\":\"2020-09-14T14:07:49+00:00\",\"dateModified\":\"2021-08-19T08:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Blog_BFE.jpg\",\"contentUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Blog_BFE.jpg\",\"width\":1600,\"height\":552},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/comprendre-la-therapie-en-tant-que-processus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/le-shiatsu-une-methode-de-la-therapie-complementaire\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprendre la th\u00e9rapie en tant que processus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"description\":\"Shiatsu, eine Methode der Komplement\u00e4rTherapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"contentUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"width\":387,\"height\":130,\"caption\":\"Shiatsu Gesellschaft Schweiz\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shiatsugesellschaftschweiz\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ab3e3b203dc15a09f4da553818d7ffb9\",\"name\":\"Therapeutenliste Manager\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"caption\":\"Therapeutenliste Manager\"},\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/author\\\/gsshiatsuverband-ch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/","og_locale":"fr_FR","og_type":"article","og_title":"Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz","og_description":"Dans la th\u00e9rapie compl\u00e9mentaire, la gu\u00e9rison est interpr\u00e9t\u00e9e comme un processus de transformation individuel qui englobe le corps, l\u2019\u00e2me et l\u2019esprit et qui est influenc\u00e9 par diff\u00e9rents facteurs qui se compl\u00e8tent mutuellement. La th\u00e9rapie a comme objectif d\u2019initier ce processus, de lui accorder de l\u2019espace et de l\u2019accompagner \u00e0 travers diverses phases. Elle vise \u00e0 stimuler la perception et la prise de conscience de soi, \u00e0 renforcer l\u2019autor\u00e9gulation et \u00e0 consolider la comp\u00e9tence personnelle de gu\u00e9rison dans l\u2019objectif de rem\u00e9dier aux restrictions et aux troubles physiques, \u00e9motionnelles et mentales. Le processus de gu\u00e9rison personnel est en outre soutenu par le renforcement de ressources et de capacit\u00e9s individuelles.","og_url":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/","og_site_name":"Shiatsu Gesellschaft Schweiz","article_publisher":"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz","article_published_time":"2020-09-14T14:07:49+00:00","article_modified_time":"2021-08-19T08:29:00+00:00","og_image":[{"width":1600,"height":552,"url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg","type":"image\/jpeg"}],"author":"Therapeutenliste Manager","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Therapeutenliste Manager","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#article","isPartOf":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/"},"author":{"name":"Therapeutenliste Manager","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/person\/ab3e3b203dc15a09f4da553818d7ffb9"},"headline":"Comprendre la th\u00e9rapie en tant que processus","datePublished":"2020-09-14T14:07:49+00:00","dateModified":"2021-08-19T08:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/"},"wordCount":1708,"publisher":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#organization"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#primaryimage"},"thumbnailUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg","articleSection":["Pratique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/","url":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/","name":"Comprendre la th\u00e9rapie en tant que processus - Shiatsu Gesellschaft Schweiz","isPartOf":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#primaryimage"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#primaryimage"},"thumbnailUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg","datePublished":"2020-09-14T14:07:49+00:00","dateModified":"2021-08-19T08:29:00+00:00","breadcrumb":{"@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#primaryimage","url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg","contentUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2020\/09\/Blog_BFE.jpg","width":1600,"height":552},{"@type":"BreadcrumbList","@id":"https:\/\/shiatsuverband.ch\/fr\/comprendre-la-therapie-en-tant-que-processus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shiatsuverband.ch\/fr\/le-shiatsu-une-methode-de-la-therapie-complementaire\/"},{"@type":"ListItem","position":2,"name":"Comprendre la th\u00e9rapie en tant que processus"}]},{"@type":"WebSite","@id":"https:\/\/shiatsuverband.ch\/fr\/#website","url":"https:\/\/shiatsuverband.ch\/fr\/","name":"Shiatsu Gesellschaft Schweiz","description":"Shiatsu, eine Methode der Komplement\u00e4rTherapie","publisher":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shiatsuverband.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/shiatsuverband.ch\/fr\/#organization","name":"Shiatsu Gesellschaft Schweiz","url":"https:\/\/shiatsuverband.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","contentUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","width":387,"height":130,"caption":"Shiatsu Gesellschaft Schweiz"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shiatsugesellschaftschweiz"]},{"@type":"Person","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/person\/ab3e3b203dc15a09f4da553818d7ffb9","name":"Therapeutenliste Manager","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","caption":"Therapeutenliste Manager"},"url":"https:\/\/shiatsuverband.ch\/fr\/author\/gsshiatsuverband-ch\/"}]}},"_links":{"self":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/40583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/comments?post=40583"}],"version-history":[{"count":5,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/40583\/revisions"}],"predecessor-version":[{"id":56591,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/40583\/revisions\/56591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/media\/40572"}],"wp:attachment":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/media?parent=40583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/categories?post=40583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/tags?post=40583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}