{"id":71745,"date":"2022-10-17T11:14:21","date_gmt":"2022-10-17T09:14:21","guid":{"rendered":"https:\/\/shiatsuverband.ch\/?p=71745"},"modified":"2022-10-24T10:05:26","modified_gmt":"2022-10-24T08:05:26","slug":"exemple-pratique-shiatsu-en-cas-de-desir-denfant","status":"publish","type":"post","link":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/","title":{"rendered":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&rsquo;enfant ?"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k0f7b5nc-7f579dfd80e5e1bd7be757955957e195\">\n.avia-image-container.av-k0f7b5nc-7f579dfd80e5e1bd7be757955957e195 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k0f7b5nc-7f579dfd80e5e1bd7be757955957e195 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k0f7b5nc-7f579dfd80e5e1bd7be757955957e195 av-styling- avia-align-center  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-71791 avia-img-lazy-loading-not-71791 avia_image ' src=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg\" alt='' title='Vorlage_Hintergrund_Blog'  height=\"552\" width=\"1600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg 1600w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-300x104.jpg 300w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-1030x355.jpg 1030w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-768x265.jpg 768w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-1536x530.jpg 1536w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-1500x518.jpg 1500w, https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu-705x243.jpg 705w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div><\/div><\/div>\n<section  class='av_textblock_section av-k0f7brzh-b44bbfe0904a29f24b6e4d72c52ad7d2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&rsquo;enfant ?<\/h1>\n<p>Nombre de couples ne d\u00e9couvrent qu\u2019un d\u00e9sir d&rsquo;enfant ne se r\u00e9alise pas toujours ou en tout cas souvent pas tout de suite uniquement lorsqu&rsquo;ils sont eux-m\u00eames concern\u00e9s. En Suisse, un couple sur six a des difficult\u00e9s \u00e0 concevoir un enfant. Dans la plupart des cas, il ne s&rsquo;agit pas d&rsquo;une infertilit\u00e9 totale, mais d&rsquo;un trouble de la fertilit\u00e9. Que le couple opte ou non pour une th\u00e9rapie m\u00e9dicale de fertilit\u00e9, le Shiatsu, de par son approche globale, peut apporter une contribution importante, comme le montrent les exemples suivants tir\u00e9s de la pratique.<\/p>\n<p>La gyn\u00e9cologue de Wanda (30 ans) lui a recommand\u00e9 le Shiatsu pour \u00ab\u00a0all\u00e9ger\u00a0\u00bb les phases \u00e9prouvantes de la th\u00e9rapie de fertilit\u00e9. Une expression bien choisie, puisqu&rsquo;elle se sentait en effet \u00ab\u00a0l\u00e9g\u00e8re comme une plume\u00a0\u00bb apr\u00e8s chaque s\u00e9ance.<br \/>\nWanda ne souffrait pas seulement de raideur physique et de fatigue, mais elle \u00e9tait aussi totalement d\u00e9pass\u00e9e par les exigences de son travail, souvent m\u00eame au bout de ses forces. Son cycle \u00e9tait tr\u00e8s irr\u00e9gulier, elle manquait de sommeil, de motivation et parfois aussi de joie de vivre.<br \/>\nAu d\u00e9but, Wanda \u00e9tait sceptique et ne croyait pas vraiment que le Shiatsu puisse lui apporter autre chose qu&rsquo;une d\u00e9tente momentan\u00e9e.<br \/>\nTrois jours apr\u00e8s le premier traitement, Wanda a \u00e9crit un feed-back d\u00e9taill\u00e9 \u00e0 la th\u00e9rapeute. Pas grand-chose n&rsquo;avait chang\u00e9 d&rsquo;apr\u00e8s elle, si ce n&rsquo;est qu&rsquo;elle avait pu dormir deux nuits compl\u00e8tes, ce qu\u2019elle n\u2019avait pas pu faire depuis longtemps, que ses maux de t\u00eate s&rsquo;\u00e9taient calm\u00e9s et que ses r\u00e8gles \u00e9taient arriv\u00e9es \u00e0 l&rsquo;heure et sans douleur.<br \/>\nBien que le premier traitement ait d\u00e9j\u00e0 am\u00e9lior\u00e9 certains aspects de ses sympt\u00f4mes, Wanda ne l&rsquo;avait apparemment pas vraiment remarqu\u00e9.<br \/>\nLes quatre s\u00e9ances qui ont suivies \u00e0 deux semaines d&rsquo;intervalle, ont chang\u00e9 sa perception de soi et le ressenti de cette jeune femme de mani\u00e8re fondamentale.<br \/>\nAttentive et int\u00e9ress\u00e9e, elle a commenc\u00e9 \u00e0 percevoir et enregistrer ce qui se passait dans son corps. La d\u00e9tente qu&rsquo;elle ressentait dans son \u00eatre entier apr\u00e8s les traitements est devenue un plaisir pour elle.<br \/>\nApr\u00e8s la deuxi\u00e8me ins\u00e9mination, Wanda est tomb\u00e9e enceinte et l&rsquo;est rest\u00e9e. Elle avait du mal \u00e0 y croire. Elle a v\u00e9cu une grossesse sans le moindre probl\u00e8me et un tr\u00e8s bel accouchement. Sur le faire-part de naissance, on pouvait lire : \u00ab\u00a0Sans le Shiatsu, ce miracle n&rsquo;aurait pas eu lieu\u00a0\u00bb.<\/p>\n<p>Il en a \u00e9t\u00e9 autrement pour X\u00e9nia et Zo\u00e9. Dans les deux cas, le partenaire avait un d\u00e9faut g\u00e9n\u00e9tique qui peut \u00eatre transmis aux enfants dans 50% des cas.<br \/>\nLes maladies ou d\u00e9ficiences potentielles encourues par les enfants seraient tr\u00e8s graves, si bien qu&rsquo;aucun des couples ne voulait prendre ce risque.<br \/>\nLes deux avaient utilis\u00e9 une contraception jusqu&rsquo;\u00e0 ce qu&rsquo;ils souhaitaient avoir un enfant. Et maintenant, il s&rsquo;agissait de suivre la m\u00eame proc\u00e9dure que les couples dont le d\u00e9sir d&rsquo;enfant n&rsquo;\u00e9tait pas satisfait. Les deux femmes ont \u00e9t\u00e9 stimul\u00e9es hormonalement, puis une ponction ovarienne a \u00e9t\u00e9 effectu\u00e9e pour recueillir les ovules, suivie d&rsquo;une f\u00e9condation in vitro. Ensuite, les ovules f\u00e9cond\u00e9s devaient \u00eatre examin\u00e9s avant qu\u2019un embryon \u00ab\u00a0sain\u00a0\u00bb puisse \u00eatre transf\u00e9r\u00e9 dans l&rsquo;ut\u00e9rus.<\/p>\n<p>Ce temps d&rsquo;attente jusqu&rsquo;\u00e0 ce que les r\u00e9sultats des tests soient disponibles est tr\u00e8s difficile pour la plupart des couples et, selon la nature des r\u00e9sultats, il peut \u00eatre \u00e9prouvant, voire d\u00e9moralisant.<br \/>\nCe fut aussi le cas pour X\u00e9nia et Zo\u00e9. Elles \u00e9taient toutes deux tr\u00e8s bien inform\u00e9es, surtout pour ce qui est des statistiques sur le sujet. D&rsquo;une certaine mani\u00e8re, ces chiffres semblaient leur donner un appui.<br \/>\nToutes deux ont eu besoin de deux ponctions avant qu&rsquo;un embryon sain \u2212 du moins sans le d\u00e9faut g\u00e9n\u00e9tique connu \u2212 puisse \u00eatre transf\u00e9r\u00e9.<br \/>\nPour Zo\u00e9, 33 ans, le transfert a fonctionn\u00e9 d\u00e8s la premi\u00e8re tentative et la grossesse a \u00e9t\u00e9 une bonne p\u00e9riode pour cette jeune m\u00e8re. X\u00e9nia, 28 ans, a subi une fausse couche \u00e0 la 7\u00e8me semaine, mais lors du deuxi\u00e8me transfert, \u00e7a a march\u00e9 et la grossesse s&rsquo;est d\u00e9roul\u00e9e sans probl\u00e8me.<\/p>\n<p>Avec les possibilit\u00e9s croissantes du diagnostic pr\u00e9implantatoire, nous sommes confront\u00e9s \u00e0 des th\u00e8mes diff\u00e9rents et nouveaux. Les d\u00e9tours n\u00e9cessaires qu&rsquo;ont d\u00fb faire ces deux femmes en sont un exemple : utiliser d&rsquo;abord des moyens de contraception pour ne pas tomber enceinte, puis devoir subir un traitement tr\u00e8s contraignant pour \u00eatre s\u00fbr d&rsquo;avoir un enfant en bonne sant\u00e9.<\/p>\n<p>Les femmes se posent souvent des questions importantes tout au long de ce processus. De nombreux \u00e9l\u00e9ments sont tr\u00e8s abstraits ou rel\u00e8vent d&rsquo;un savoir trop sp\u00e9cifique pour les personnes concern\u00e9es et ne peuvent pas \u00eatre vraiment compris, m\u00eame dans le meilleur des entretiens \u2212 ils doivent aussi \u00eatre v\u00e9cus. C&rsquo;est pourquoi une partie de l&rsquo;accompagnement Shiatsu consiste aussi \u00e0 aider les femmes \u00e0 concr\u00e9tiser et \u00e0 formuler leurs questions afin qu&rsquo;elles puissent les poser clairement aux m\u00e9decins sp\u00e9cialistes. Cette clarification permet aux femmes de se lib\u00e9rer de leurs inqui\u00e9tudes et de leurs peurs, de mieux pouvoir l\u00e2cher prise et de ne pas devoir se pr\u00e9occuper. Un \u00e9tat dans lequel l&rsquo;efficacit\u00e9 du Shiatsu peut se d\u00e9ployer de mani\u00e8re optimale et o\u00f9 une conception et une grossesse r\u00e9ussie sont d&rsquo;autant plus probables.<\/p>\n<p><em>Charlotte Huggel<\/em><\/p>\n<\/div><\/section>\n<section  class='av_textblock_section av-l9cjph2b-54769d7464198922142399d167f6c052 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Articles \u00e0 ce sujet\u00a0<\/strong><br \/>\n<a href=\"https:\/\/shiatsuverband.ch\/fr\/shiatsu-et-desir-denfant-donner-de-lespace-et-du-temps\/\" target=\"_blank\" rel=\"noopener\">_Shiatsu et d\u00e9sir d\u2019enfant : donner de l\u2019espace et du temps<\/a><br \/>\n<a href=\"https:\/\/shiatsuverband.ch\/fr\/le-shiatsu-pendant-la-grossesse\/\" target=\"_blank\" rel=\"noopener\">_Le Shiatsu pendant la grossesse<\/a><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Nombre de couples ne d\u00e9couvrent qu\u2019un d\u00e9sir d&rsquo;enfant ne se r\u00e9alise pas toujours ou en tout cas souvent pas tout de suite uniquement lorsqu&rsquo;ils sont eux-m\u00eames concern\u00e9s. En Suisse, un couple sur six a des difficult\u00e9s \u00e0 concevoir un enfant. Dans la plupart des cas, il ne s&rsquo;agit pas d&rsquo;une infertilit\u00e9 totale, mais d&rsquo;un trouble de la fertilit\u00e9. Que le couple opte ou non pour une th\u00e9rapie m\u00e9dicale de fertilit\u00e9, le Shiatsu, de par son approche globale, peut apporter une contribution importante, comme le montrent les exemples suivants tir\u00e9s de la pratique.<\/p>\n","protected":false},"author":5,"featured_media":71791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21,36],"tags":[],"class_list":["post-71745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-methode-2","category-methode-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&#039;enfant ? - Shiatsu Gesellschaft Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&#039;enfant ? - Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"og:description\" content=\"Nombre de couples ne d\u00e9couvrent qu\u2019un d\u00e9sir d&#039;enfant ne se r\u00e9alise pas toujours ou en tout cas souvent pas tout de suite uniquement lorsqu&#039;ils sont eux-m\u00eames concern\u00e9s. En Suisse, un couple sur six a des difficult\u00e9s \u00e0 concevoir un enfant. Dans la plupart des cas, il ne s&#039;agit pas d&#039;une infertilit\u00e9 totale, mais d&#039;un trouble de la fertilit\u00e9. Que le couple opte ou non pour une th\u00e9rapie m\u00e9dicale de fertilit\u00e9, le Shiatsu, de par son approche globale, peut apporter une contribution importante, comme le montrent les exemples suivants tir\u00e9s de la pratique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/\" \/>\n<meta property=\"og:site_name\" content=\"Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T09:14:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-24T08:05:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Therapeutenliste Manager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Therapeutenliste Manager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/\"},\"author\":{\"name\":\"Therapeutenliste Manager\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ab3e3b203dc15a09f4da553818d7ffb9\"},\"headline\":\"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&rsquo;enfant ?\",\"datePublished\":\"2022-10-17T09:14:21+00:00\",\"dateModified\":\"2022-10-24T08:05:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/\"},\"wordCount\":1359,\"publisher\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Titelbild_Ersatz_Kiwu.jpg\",\"articleSection\":[\"M\u00e9thode\",\"Methode\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/\",\"name\":\"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d'enfant ? - Shiatsu Gesellschaft Schweiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Titelbild_Ersatz_Kiwu.jpg\",\"datePublished\":\"2022-10-17T09:14:21+00:00\",\"dateModified\":\"2022-10-24T08:05:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Titelbild_Ersatz_Kiwu.jpg\",\"contentUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Titelbild_Ersatz_Kiwu.jpg\",\"width\":1600,\"height\":552},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/le-shiatsu-une-methode-de-la-therapie-complementaire\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&#8217;enfant ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"description\":\"Shiatsu, eine Methode der Komplement\u00e4rTherapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"contentUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"width\":387,\"height\":130,\"caption\":\"Shiatsu Gesellschaft Schweiz\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shiatsugesellschaftschweiz\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ab3e3b203dc15a09f4da553818d7ffb9\",\"name\":\"Therapeutenliste Manager\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g\",\"caption\":\"Therapeutenliste Manager\"},\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/author\\\/gsshiatsuverband-ch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d'enfant ? - Shiatsu Gesellschaft Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/","og_locale":"fr_FR","og_type":"article","og_title":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d'enfant ? - Shiatsu Gesellschaft Schweiz","og_description":"Nombre de couples ne d\u00e9couvrent qu\u2019un d\u00e9sir d'enfant ne se r\u00e9alise pas toujours ou en tout cas souvent pas tout de suite uniquement lorsqu'ils sont eux-m\u00eames concern\u00e9s. En Suisse, un couple sur six a des difficult\u00e9s \u00e0 concevoir un enfant. Dans la plupart des cas, il ne s'agit pas d'une infertilit\u00e9 totale, mais d'un trouble de la fertilit\u00e9. Que le couple opte ou non pour une th\u00e9rapie m\u00e9dicale de fertilit\u00e9, le Shiatsu, de par son approche globale, peut apporter une contribution importante, comme le montrent les exemples suivants tir\u00e9s de la pratique.","og_url":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/","og_site_name":"Shiatsu Gesellschaft Schweiz","article_publisher":"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz","article_published_time":"2022-10-17T09:14:21+00:00","article_modified_time":"2022-10-24T08:05:26+00:00","og_image":[{"width":1600,"height":552,"url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg","type":"image\/jpeg"}],"author":"Therapeutenliste Manager","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Therapeutenliste Manager","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#article","isPartOf":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/"},"author":{"name":"Therapeutenliste Manager","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/person\/ab3e3b203dc15a09f4da553818d7ffb9"},"headline":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&rsquo;enfant ?","datePublished":"2022-10-17T09:14:21+00:00","dateModified":"2022-10-24T08:05:26+00:00","mainEntityOfPage":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/"},"wordCount":1359,"publisher":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#organization"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#primaryimage"},"thumbnailUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg","articleSection":["M\u00e9thode","Methode"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/","url":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/","name":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d'enfant ? - Shiatsu Gesellschaft Schweiz","isPartOf":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#primaryimage"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#primaryimage"},"thumbnailUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg","datePublished":"2022-10-17T09:14:21+00:00","dateModified":"2022-10-24T08:05:26+00:00","breadcrumb":{"@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#primaryimage","url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg","contentUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2022\/10\/Titelbild_Ersatz_Kiwu.jpg","width":1600,"height":552},{"@type":"BreadcrumbList","@id":"https:\/\/shiatsuverband.ch\/fr\/exemple-pratique-shiatsu-en-cas-de-desir-denfant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shiatsuverband.ch\/fr\/le-shiatsu-une-methode-de-la-therapie-complementaire\/"},{"@type":"ListItem","position":2,"name":"Exemple pratique : Comment le Shiatsu aide-t-il en cas de d\u00e9sir d&#8217;enfant ?"}]},{"@type":"WebSite","@id":"https:\/\/shiatsuverband.ch\/fr\/#website","url":"https:\/\/shiatsuverband.ch\/fr\/","name":"Shiatsu Gesellschaft Schweiz","description":"Shiatsu, eine Methode der Komplement\u00e4rTherapie","publisher":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shiatsuverband.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/shiatsuverband.ch\/fr\/#organization","name":"Shiatsu Gesellschaft Schweiz","url":"https:\/\/shiatsuverband.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","contentUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","width":387,"height":130,"caption":"Shiatsu Gesellschaft Schweiz"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shiatsugesellschaftschweiz"]},{"@type":"Person","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/person\/ab3e3b203dc15a09f4da553818d7ffb9","name":"Therapeutenliste Manager","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/975aecfee28b5835b25498f09a9da6996a78ec2eb640e20d82301415880d9599?s=96&d=mm&r=g","caption":"Therapeutenliste Manager"},"url":"https:\/\/shiatsuverband.ch\/fr\/author\/gsshiatsuverband-ch\/"}]}},"_links":{"self":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/71745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/comments?post=71745"}],"version-history":[{"count":3,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/71745\/revisions"}],"predecessor-version":[{"id":71747,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/posts\/71745\/revisions\/71747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/media\/71791"}],"wp:attachment":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/media?parent=71745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/categories?post=71745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/tags?post=71745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}