{"id":127392,"date":"2026-05-12T14:16:21","date_gmt":"2026-05-12T12:16:21","guid":{"rendered":"https:\/\/shiatsuverband.ch\/therapeuten\/irene-scheidegger\/"},"modified":"2026-05-12T14:16:21","modified_gmt":"2026-05-12T12:16:21","slug":"irene-scheidegger","status":"publish","type":"therapeuten","link":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/","title":{"rendered":"Irene Scheidegger"},"template":"","class_list":["post-127392","therapeuten","type-therapeuten","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Irene Scheidegger - Shiatsu Gesellschaft Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irene Scheidegger - Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"og:description\" content=\"Irene Scheidegger Raum f\u00fcr Shiatsu Schwanengasse 4 3011 Bern 078 718 10 28 shiatsu@shiatsu-irene.com www.shiatsu-irene.com Eidg. Diplom KT Branchenzertifikat OdA KT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/\" \/>\n<meta property=\"og:site_name\" content=\"Shiatsu Gesellschaft Schweiz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/therapeuten\\\/irene-scheidegger\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/therapeuten\\\/irene-scheidegger\\\/\",\"name\":\"Irene Scheidegger - Shiatsu Gesellschaft Schweiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\"},\"datePublished\":\"2026-05-12T12:16:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/therapeuten\\\/irene-scheidegger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/therapeuten\\\/irene-scheidegger\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/therapeuten\\\/irene-scheidegger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/le-shiatsu-une-methode-de-la-therapie-complementaire\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irene Scheidegger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"description\":\"Shiatsu, eine Methode der Komplement\u00e4rTherapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#organization\",\"name\":\"Shiatsu Gesellschaft Schweiz\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"contentUrl\":\"https:\\\/\\\/shiatsuverband.ch\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Shiatsuverband_Logo.png\",\"width\":387,\"height\":130,\"caption\":\"Shiatsu Gesellschaft Schweiz\"},\"image\":{\"@id\":\"https:\\\/\\\/shiatsuverband.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shiatsugesellschaftschweiz\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irene Scheidegger - Shiatsu Gesellschaft Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/","og_locale":"fr_FR","og_type":"article","og_title":"Irene Scheidegger - Shiatsu Gesellschaft Schweiz","og_description":"Irene Scheidegger Raum f\u00fcr Shiatsu Schwanengasse 4 3011 Bern 078 718 10 28 shiatsu@shiatsu-irene.com www.shiatsu-irene.com Eidg. Diplom KT Branchenzertifikat OdA KT","og_url":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/","og_site_name":"Shiatsu Gesellschaft Schweiz","article_publisher":"https:\/\/www.facebook.com\/shiatsugesellschaftschweiz","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/","url":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/","name":"Irene Scheidegger - Shiatsu Gesellschaft Schweiz","isPartOf":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#website"},"datePublished":"2026-05-12T12:16:21+00:00","breadcrumb":{"@id":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/shiatsuverband.ch\/fr\/therapeuten\/irene-scheidegger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shiatsuverband.ch\/fr\/le-shiatsu-une-methode-de-la-therapie-complementaire\/"},{"@type":"ListItem","position":2,"name":"Irene Scheidegger"}]},{"@type":"WebSite","@id":"https:\/\/shiatsuverband.ch\/fr\/#website","url":"https:\/\/shiatsuverband.ch\/fr\/","name":"Shiatsu Gesellschaft Schweiz","description":"Shiatsu, eine Methode der Komplement\u00e4rTherapie","publisher":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shiatsuverband.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/shiatsuverband.ch\/fr\/#organization","name":"Shiatsu Gesellschaft Schweiz","url":"https:\/\/shiatsuverband.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","contentUrl":"https:\/\/shiatsuverband.ch\/wp-content\/uploads\/2019\/04\/Shiatsuverband_Logo.png","width":387,"height":130,"caption":"Shiatsu Gesellschaft Schweiz"},"image":{"@id":"https:\/\/shiatsuverband.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shiatsugesellschaftschweiz"]}]}},"_links":{"self":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/therapeuten\/127392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/therapeuten"}],"about":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/types\/therapeuten"}],"wp:attachment":[{"href":"https:\/\/shiatsuverband.ch\/fr\/wp-json\/wp\/v2\/media?parent=127392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}